{"id":507,"count":15,"description":"","link":"https:\/\/www.lifescienceart.com\/cs\/science\/medical-technology\/","name":"Zdravotnick\u00e1 technologie","slug":"medical-technology","taxonomy":"category","parent":3,"meta":[],"_links":{"self":[{"href":"https:\/\/www.lifescienceart.com\/cs\/wp-json\/wp\/v2\/categories\/507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lifescienceart.com\/cs\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.lifescienceart.com\/cs\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.lifescienceart.com\/cs\/wp-json\/wp\/v2\/categories\/3"}],"wp:post_type":[{"href":"https:\/\/www.lifescienceart.com\/cs\/wp-json\/wp\/v2\/posts?categories=507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}