{"id":22434,"count":1,"description":"","link":"https:\/\/www.lifescienceart.com\/da\/tag\/weird-and-wonderful\/","name":"M\u00e6rkeligt og vidunderligt","slug":"weird-and-wonderful","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.lifescienceart.com\/da\/wp-json\/wp\/v2\/tags\/22434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lifescienceart.com\/da\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.lifescienceart.com\/da\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.lifescienceart.com\/da\/wp-json\/wp\/v2\/posts?tags=22434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}