{"id":14164,"date":"2024-07-02T09:31:20","date_gmt":"2024-07-02T09:31:20","guid":{"rendered":"https:\/\/www.lifescienceart.com\/?p=14164"},"modified":"2024-07-02T09:31:20","modified_gmt":"2024-07-02T09:31:20","slug":"lost-monastery-revealed-through-medieval-game-board","status":"publish","type":"post","link":"https:\/\/www.lifescienceart.com\/de\/uncategorized\/lost-monastery-revealed-through-medieval-game-board\/","title":{"rendered":"Mittelalter-Krimi gel\u00f6st: Spielbrett enth\u00fcllt Standort von verschollenem Kloster"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Mittelalterliches Mysterium: Spielbrett enth\u00fcllt verschollenes Kloster<\/h2>\n\n<h2 class=\"wp-block-heading\">Arch\u00e4ologische Entdeckung<\/h2>\n\n<p>In den sanften H\u00fcgeln von Aberdeenshire, Schottland, sind Arch\u00e4ologen auf einen mittelalterlichen Schatz gesto\u00dfen, der den Schl\u00fcssel zu einem jahrhundertealten R\u00e4tsel enthalten k\u00f6nnte. Bei ihrer Suche nach dem verschollenen Kloster von Deer entdeckten sie ein seltenes mittelalterliches Spielbrett, das den wahren Standort des Klosters vermuten l\u00e4sst.<\/p>\n\n<h2 class=\"wp-block-heading\">Das r\u00e4tselhafte Spielbrett<\/h2>\n\n<p>Das scheibenf\u00f6rmige Spielbrett, von dem angenommen wird, dass es von M\u00f6nchen zum Spielen von Hnefatafl genutzt wurde, stammt aus dem 7. oder 8. Jahrhundert zur\u00fcck. Radiokarbondatierung hat sein Alter best\u00e4tigt, wodurch es mehrere hundert Jahre \u00e4lter ist als das ber\u00fchmte Book of Deer, ein Manuskript, das von M\u00f6nchen im Kloster geschrieben wurde.<\/p>\n\n<h2 class=\"wp-block-heading\">Hnefatafl: Ein nordisches Strategiespiel<\/h2>\n\n<p>Hnefatafl war ein beliebtes Strategiespiel bei den Wikingern und anderen nordischen Kulturen. Es beinhaltet einen K\u00f6nig und seine Verteidiger, die sich einer gr\u00f6\u00dferen Anzahl von Angreifern gegen\u00fcberstehen. Das Ziel des K\u00f6nigs ist es, einen sicheren Ort in einer der vier Ecken des Spielbretts zu erreichen, w\u00e4hrend die Angreifer darauf abzielen, ihn gefangen zu nehmen.<\/p>\n\n<h2 class=\"wp-block-heading\">Hinweise aus der Holzkohle<\/h2>\n\n<p>Neben dem Spielbrett entdeckten Arch\u00e4ologen Holzkohlefragmente, die aus derselben Zeit stammen. Dies liefert weitere Beweise daf\u00fcr, dass die Ausgrabungsst\u00e4tte w\u00e4hrend des Mittelalters aktiv war. Fr\u00fchere Ausgrabungen hatten auch Keramik- und Holzkohlefragmente aus dem 12. Jahrhundert freigelegt, was darauf hindeutet, dass der Ort \u00fcber einen l\u00e4ngeren Zeitraum bewohnt war.<\/p>\n\n<h2 class=\"wp-block-heading\">Sprachliche Hinweise aus dem Book of Deer<\/h2>\n\n<p>Das Book of Deer, das im 10. Jahrhundert geschrieben wurde, enth\u00e4lt den fr\u00fchesten bekannten schriftlichen Beweis f\u00fcr schottisches G\u00e4lisch. Linguisten haben die g\u00e4lischen Notationen in dem Buch analysiert und festgestellt, dass sie sich von fr\u00fcheren Manuskripten unterscheiden, was darauf hindeutet, dass sich die schottische und irische g\u00e4lische Sprache zu dieser Zeit zu trennen begannen.<\/p>\n\n<h2 class=\"wp-block-heading\">Die Bedeutung der Entdeckung<\/h2>\n\n<p>Die Entdeckung des Spielbretts und der Holzkohlefragmente liefert verlockende Beweise daf\u00fcr, dass die Ausgrabungsst\u00e4tte tats\u00e4chlich der Standort des verschollenen Klosters von Deer war. Arch\u00e4ologen warnen jedoch davor, dass weitere Beweise erforderlich sind, um eine endg\u00fcltige Verbindung zwischen dem Brett und dem Kloster herzustellen.<\/p>\n\n<h2 class=\"wp-block-heading\">Laufende Ausgrabungen<\/h2>\n\n<p>Das Book of Deer Project, eine lokale Initiative, die seit 2008 nach dem verschollenen Kloster sucht, sammelt jetzt Spenden f\u00fcr weitere Ausgrabungen. Sie hoffen, mehr Hinweise aufzudecken, die ihnen helfen werden, den genauen Standort des Klosters zu bestimmen und Licht in diese r\u00e4tselhafte Zeit der schottischen Geschichte zu bringen.<\/p>\n\n<h2 class=\"wp-block-heading\">Ein Verm\u00e4chtnis f\u00fcr die Zukunft<\/h2>\n\n<p>Trotz seiner geringen Gr\u00f6\u00dfe hat das Book of Deer ein bleibendes Verm\u00e4chtnis hinterlassen. Es bietet wertvolle Einblicke in die Geschichte und Kultur des mittelalterlichen Schottlands, und die j\u00fcngste Entdeckung des Spielbretts f\u00fcgt seiner Geschichte ein weiteres faszinierendes Kapitel hinzu. W\u00e4hrend Arch\u00e4ologen sich weiterhin mit den Geheimnissen der Vergangenheit befassen, wird das verschollene Kloster von Deer m\u00f6glicherweise bald seine Geheimnisse preisgeben und uns einen Einblick in das Leben derer bieten, die vor Jahrhunderten in seinen Mauern lebten und arbeiteten.<\/p>","protected":false},"excerpt":{"rendered":"<p>Mittelalterliches Mysterium: Spielbrett enth\u00fcllt verschollenes Kloster Arch\u00e4ologische Entdeckung In den sanften H\u00fcgeln von Aberdeenshire, Schottland, sind Arch\u00e4ologen auf einen mittelalterlichen Schatz gesto\u00dfen, der den Schl\u00fcssel zu einem jahrhundertealten R\u00e4tsel enthalten&hellip;<\/p>\n","protected":false},"author":1,"featured_media":23768,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[88,19050,19049,6462,19046,19047,19051,19048],"class_list":["post-14164","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-archaeology","tag-book-of-deer","tag-hnefatafl","tag-linguistics","tag-medieval-scotland","tag-monastery","tag-scottish-gaelic","tag-game-board"],"_links":{"self":[{"href":"https:\/\/www.lifescienceart.com\/de\/wp-json\/wp\/v2\/posts\/14164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lifescienceart.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lifescienceart.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lifescienceart.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lifescienceart.com\/de\/wp-json\/wp\/v2\/comments?post=14164"}],"version-history":[{"count":1,"href":"https:\/\/www.lifescienceart.com\/de\/wp-json\/wp\/v2\/posts\/14164\/revisions"}],"predecessor-version":[{"id":14165,"href":"https:\/\/www.lifescienceart.com\/de\/wp-json\/wp\/v2\/posts\/14164\/revisions\/14165"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lifescienceart.com\/de\/wp-json\/wp\/v2\/media\/23768"}],"wp:attachment":[{"href":"https:\/\/www.lifescienceart.com\/de\/wp-json\/wp\/v2\/media?parent=14164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lifescienceart.com\/de\/wp-json\/wp\/v2\/categories?post=14164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lifescienceart.com\/de\/wp-json\/wp\/v2\/tags?post=14164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}