{"id":6754,"date":"2020-11-10T03:46:40","date_gmt":"2020-11-10T03:46:40","guid":{"rendered":"https:\/\/www.lifescienceart.com\/?p=6754"},"modified":"2020-11-10T03:46:40","modified_gmt":"2020-11-10T03:46:40","slug":"how-to-clean-car-windows-and-get-them-shining-like-new","status":"publish","type":"post","link":"https:\/\/www.lifescienceart.com\/de\/science\/transportation\/how-to-clean-car-windows-and-get-them-shining-like-new\/","title":{"rendered":"So reinigen Sie Autofenster und bringen sie zum Gl\u00e4nzen wie neu"},"content":{"rendered":"<h2 class=\"wp-block-heading\">So reinigen Sie Autofenster und bringen sie zum Gl\u00e4nzen wie neu<\/h2>\n\n<p>Saubere Autofenster sind nicht nur wichtig f\u00fcr die \u00c4sthetik, sondern auch f\u00fcr die Sicherheit. Verschmutzte Fenster k\u00f6nnen Ihre Sicht w\u00e4hrend der Fahrt beeintr\u00e4chtigen und es schwierig machen, andere Fahrzeuge, Fu\u00dfg\u00e4nger und Verkehrszeichen zu sehen. Gl\u00fccklicherweise ist die Reinigung Ihrer Autofenster eine relativ einfache und kosteng\u00fcnstige Aufgabe, die Sie zu Hause mit ein paar grundlegenden Hilfsmitteln erledigen k\u00f6nnen.<\/p>\n\n<h3 class=\"wp-block-heading\">Was Sie ben\u00f6tigen<\/h3>\n\n<h2 class=\"wp-block-heading\">Ausr\u00fcstung \/ Werkzeuge:<\/h2>\n\n<ul class=\"wp-block-list\">\n<li>2 bis 4 Mikrofasert\u00fccher<\/li>\n<li>Staubsauger mit Schlauch und Polsterb\u00fcrste (optional)<\/li>\n<li>Einweg-Staubwedel<\/li>\n<li>2 Spr\u00fchflaschen<\/li>\n<li>Fensterabzieher (optional)<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\">Materialien:<\/h2>\n\n<ul class=\"wp-block-list\">\n<li>1 Flasche destillierter wei\u00dfer Essig<\/li>\n<li>1 Flasche destilliertes Wasser<\/li>\n<li>1 Flasche Isopropylalkohol<\/li>\n<li>1 Etikett<\/li>\n<li>1 Schachtel Maisst\u00e4rke<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\">Schritt-f\u00fcr-Schritt-Anleitung<\/h3>\n\n<h2 class=\"wp-block-heading\">1. Mischen Sie DIY-Glasreiniger<\/h2>\n\n<p>F\u00fcr leicht verschmutzte Fenster mischen Sie eine Tasse Reinigungsalkohol, eine Tasse destilliertes Wasser und einen Essl\u00f6ffel Essig in einer Spr\u00fchflasche. Sch\u00fctteln Sie die Flasche, um die Zutaten zu vermischen, und etikettieren Sie sie.<\/p>\n\n<p>F\u00fcr stark verschmutzte Fenster mischen Sie eine viertel Tasse Reinigungsalkohol, eine viertel Tasse destillierten wei\u00dfen Essig, einen Essl\u00f6ffel Maisst\u00e4rke und zwei Tassen destilliertes Wasser in einer Spr\u00fchflasche. Sch\u00fctteln Sie die Flasche gut, um die Zutaten zu vermischen, und etikettieren Sie sie.<\/p>\n\n<h2 class=\"wp-block-heading\">2. Entfernen Sie Staub und Schmutz von den \u00e4u\u00dferen Fenstern<\/h2>\n\n<p>Entfernen Sie mit den H\u00e4nden alle Bl\u00e4tter oder Zweige, die sich in den Scheibenwischern oder den Dichtungen der Fenster verfangen haben. Saugen Sie dann mit einem Staubsauger mit Schlauch so viel kleine R\u00fcckst\u00e4nde und Staub wie m\u00f6glich ab. Verwenden Sie abschlie\u00dfend ein trockenes Mikrofasertuch oder einen Einweg-Staubwedel, um so viel losen Schmutz und Staub wie m\u00f6glich zu entfernen.<\/p>\n\n<h2 class=\"wp-block-heading\">3. Reinigen und \u00fcberpr\u00fcfen Sie die \u00e4u\u00dferen Fenster<\/h2>\n\n<p>Bespr\u00fchen Sie ein Fenster nach dem anderen leicht mit Glasreiniger und wischen Sie das Fenster unmittelbar nach dem Aufspr\u00fchen mit einem Mikrofasertuch ab, um Tropfen zu vermeiden oder dass der Reiniger auf dem Fenster trocknet. Wischen Sie in einer Auf- und Ab- oder Seite-zu-Seite-Bewegung. Wenn Sie in kreisenden Bewegungen wischen, k\u00f6nnen Streifen entstehen.<\/p>\n\n<p>Wenn sich Vogelkot oder getrocknete Insekten befinden, geben Sie etwas mehr Glasreiniger hinzu und lassen Sie ihn etwa 60 Sekunden einwirken. \u00dcben Sie etwas Druck auf das Mikrofasertuch aus, um den Schmutz zu entfernen. \u00dcberpr\u00fcfen Sie beim Reinigen die Fenster auf rissige Dichtungen, Absplitterungen und Risse und reparieren Sie diese so schnell wie m\u00f6glich.<\/p>\n\n<h2 class=\"wp-block-heading\">4. Trocknen und polieren Sie, bis sie gl\u00e4nzen<\/h2>\n\n<p>Trocknen Sie jedes Fenster sofort nach der Reinigung mit einem sauberen, trockenen Mikrofasertuch.<\/p>\n\n<p>Oder verwenden Sie, wenn Sie mit einem Fensterabzieher vertraut sind, diesen, um die Feuchtigkeit zu entfernen. Achten Sie darauf, die Abzieherklinge nach jedem Durchgang \u00fcber das Fenster zu trocknen.<\/p>\n\n<h2 class=\"wp-block-heading\">5. Reinigen Sie die Innenfenster<\/h2>\n\n<p>Entfernen Sie im Fahrzeuginneren alle Gegenst\u00e4nde vom Armaturenbrett und jegliches Zubeh\u00f6r wie Sonnenschutz von den Fenstern und verwenden Sie ein trockenes Mikrofasertuch oder einen Staubwedel, um Staub zu entfernen.<\/p>\n\n<p>Anstatt die Fenster direkt zu bespr\u00fchen, spr\u00fchen Sie den Glasreiniger auf ein sauberes Mikrofasertuch, um das Armaturenbrett und die Innenfl\u00e4chen zu sch\u00fctzen. Reinigen und trocknen Sie ein Fenster nach dem anderen vollst\u00e4ndig, bevor Sie zum n\u00e4chsten \u00fcbergehen.<\/p>\n\n<p>Senken Sie die Fenster leicht ab und beginnen Sie oben am Fenster und arbeiten Sie sich nach unten vor, wobei Sie eventuelle Tropfen dabei auffangen. Reinigen Sie ggf. auch die \u00e4u\u00dfere Scheibe oben, falls sie noch verschmutzt ist, und wischen Sie jedes Fenster in einer Auf-und-Ab- oder Seite-zu-Seite-Bewegung ab.<\/p>\n\n<p>Zum Abschluss polieren Sie die Fenster mit einem sauberen, trockenen Mikrofasertuch auf Hochglanz.<\/p>\n\n<h3 class=\"wp-block-heading\">Tipps zur Reinigung von Autofenstern<\/h3>\n\n<ul class=\"wp-block-list\">\n<li>Vermeiden Sie es, die Fenster bei direkter Sonneneinstrahlung zu reinigen. Der Glasreiniger kann trocknen, bevor Sie fertig sind, und Streifen hinterlassen.<\/li>\n<li>Wechseln Sie die Mikrofasert\u00fccher h\u00e4ufig aus, wenn sie verschmutzt sind. Sie m\u00f6chten keinen Schmutz auf das n\u00e4chste Fenster \u00fcbertragen.<\/li>\n<li>Verwenden Sie keine Papiert\u00fccher zur Reinigung von Autofenstern, da sie Fusseln auf dem Glas hinterlassen.<\/li>\n<li>Um die unteren inneren Ecken der Windschutzscheibe zu erreichen, wickeln Sie Ihre Reinigungs- und Trockent\u00fccher um ein Lineal und befestigen Sie sie mit Gummib\u00e4ndern.<\/li>\n<li>Wenn Sie hartes Wasser haben, verwenden Sie destilliertes Wasser in Ihren selbstgemachten Glasreinigern, um Streifen und Wasserflecken zu vermeiden.<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>So reinigen Sie Autofenster und bringen sie zum Gl\u00e4nzen wie neu Saubere Autofenster sind nicht nur wichtig f\u00fcr die \u00c4sthetik, sondern auch f\u00fcr die Sicherheit. Verschmutzte Fenster k\u00f6nnen Ihre Sicht&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2773],"tags":[11199,5821,11200,99,8891,1761,2940],"class_list":["post-6754","post","type-post","status-publish","format-standard","hentry","category-transportation","tag-car-care","tag-vehicle-maintenance","tag-windows","tag-lifescienceart","tag-cleaning","tag-diy","tag-safety"],"_links":{"self":[{"href":"https:\/\/www.lifescienceart.com\/de\/wp-json\/wp\/v2\/posts\/6754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lifescienceart.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lifescienceart.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lifescienceart.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lifescienceart.com\/de\/wp-json\/wp\/v2\/comments?post=6754"}],"version-history":[{"count":1,"href":"https:\/\/www.lifescienceart.com\/de\/wp-json\/wp\/v2\/posts\/6754\/revisions"}],"predecessor-version":[{"id":6755,"href":"https:\/\/www.lifescienceart.com\/de\/wp-json\/wp\/v2\/posts\/6754\/revisions\/6755"}],"wp:attachment":[{"href":"https:\/\/www.lifescienceart.com\/de\/wp-json\/wp\/v2\/media?parent=6754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lifescienceart.com\/de\/wp-json\/wp\/v2\/categories?post=6754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lifescienceart.com\/de\/wp-json\/wp\/v2\/tags?post=6754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}