{"id":23484,"count":1,"description":"","link":"https:\/\/www.lifescienceart.com\/es\/tag\/lunar-events\/","name":"Eventos lunares","slug":"lunar-events","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.lifescienceart.com\/es\/wp-json\/wp\/v2\/tags\/23484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lifescienceart.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.lifescienceart.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.lifescienceart.com\/es\/wp-json\/wp\/v2\/posts?tags=23484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}