{"id":2121,"count":2,"description":"","link":"https:\/\/www.lifescienceart.com\/id\/science\/technology-and-society\/","name":"Teknologi dan Masyarakat","slug":"technology-and-society","taxonomy":"category","parent":3,"meta":[],"_links":{"self":[{"href":"https:\/\/www.lifescienceart.com\/id\/wp-json\/wp\/v2\/categories\/2121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lifescienceart.com\/id\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.lifescienceart.com\/id\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.lifescienceart.com\/id\/wp-json\/wp\/v2\/categories\/3"}],"wp:post_type":[{"href":"https:\/\/www.lifescienceart.com\/id\/wp-json\/wp\/v2\/posts?categories=2121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}