{"id":2256,"date":"2024-09-09T22:39:14","date_gmt":"2024-09-09T22:39:14","guid":{"rendered":"https:\/\/www.lifescienceart.com\/?p=2256"},"modified":"2024-09-09T22:39:14","modified_gmt":"2024-09-09T22:39:14","slug":"yellowstone-national-park-flooding-forces-closures-evacuations","status":"publish","type":"post","link":"https:\/\/www.lifescienceart.com\/it\/science\/earth-science\/yellowstone-national-park-flooding-forces-closures-evacuations\/","title":{"rendered":"Alluvioni estreme devastano il Parco Nazionale di Yellowstone"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Alluvioni estreme devastano il Parco Nazionale di Yellowstone, costringendo chiusure ed evacuazioni<\/h2>\n\n<h2 class=\"wp-block-heading\">Inondazioni senza precedenti<\/h2>\n\n<p>Il Parco Nazionale di Yellowstone \u00e8 stato colpito da inondazioni senza precedenti, costringendo alla chiusura di tutti gli ingressi del parco a causa di &#8220;condizioni estremamente pericolose&#8221;, secondo un comunicato degli enti del parco. Le condizioni meteorologiche estreme hanno inoltre causato danni significativi ad abitazioni e infrastrutture nelle comunit\u00e0 vicine al parco.<\/p>\n\n<h2 class=\"wp-block-heading\">Cause delle inondazioni<\/h2>\n\n<p>Le inondazioni sono state causate da forti piogge cadute nel fine settimana e fino a luned\u00ec, portate da un sistema di tempeste noto come &#8220;fiume atmosferico&#8221;. Questa ondata di umidit\u00e0 concentrata \u00e8 arrivata dall&#8217;Oceano Pacifico e ha attraversato le Montagne Rocciose settentrionali, portando precipitazioni record anche a Washington e in Oregon la scorsa settimana.<\/p>\n\n<p>Prima della tempesta, temperature insolitamente calde nelle Montagne Rocciose hanno provocato un maggiore scioglimento della neve, che ha contribuito alle inondazioni. Il fiume Yellowstone e il suo affluente, il fiume Gardner, hanno ricevuto una quantit\u00e0 &#8220;senza precedenti&#8221; di pioggia, facendo s\u00ec che le acque del fiume Yellowstone salissero da 6 a 15 piedi in sole 24 ore.<\/p>\n\n<h2 class=\"wp-block-heading\">Danni ed evacuazioni<\/h2>\n\n<p>Le inondazioni hanno causato danni significativi a strade e ponti, incluso un ponte crollato su Rescue Creek. Si sono verificate anche frane, ostacolando ulteriormente l&#8217;accesso al parco.<\/p>\n\n<p>Case intere sono state spazzate via dalle acque alluvionali e molti residenti sono bloccati nelle loro case o sono stati evacuati. I servizi di emergenza stanno effettuando trasporti aerei per soccorrere le persone dalle loro case e dall&#8217;acqua.<\/p>\n\n<h2 class=\"wp-block-heading\">Comunit\u00e0 colpite<\/h2>\n\n<p>Le inondazioni hanno avuto un impatto devastante sulle comunit\u00e0 vicine al parco, tra cui Gardiner, Cooke City e Silver Gate, Montana. Queste citt\u00e0 sono isolate a causa di strade e ponti distrutti.<\/p>\n\n<h2 class=\"wp-block-heading\">Risposta e ripristino<\/h2>\n\n<p>Il personale del parco ha evacuato i visitatori dalla parte settentrionale del parco, dove si sono verificati molteplici cedimenti di strade e ponti, frane e altri problemi. Hanno inoltre allontanato i visitatori dal circuito meridionale del parco a causa di problemi idrici e fognari.<\/p>\n\n<p>Il governatore del Montana, Greg Gianforte, ha emesso una dichiarazione di disastro in tutto lo stato per aiutare le comunit\u00e0 colpite a riprendersi.<\/p>\n\n<h2 class=\"wp-block-heading\">Commemorazioni del 150\u00b0 anniversario interessate<\/h2>\n\n<p>Le inondazioni probabilmente influenzeranno le commemorazioni del 150\u00b0 anniversario del parco quest&#8217;anno. La sede, il museo e gli archivi del parco si trovano all&#8217;ingresso nord, attualmente chiuso. Anche l&#8217;Arco di Roosevelt, dove i gruppi di nativi americani avevano pianificato di erigere un villaggio di tende, si trova all&#8217;ingresso nord.<\/p>\n\n<h2 class=\"wp-block-heading\">Situazione attuale<\/h2>\n\n<p>Gli ingressi del parco rimarranno chiusi almeno fino a mercoled\u00ec, e forse pi\u00f9 a lungo, a seconda della gravit\u00e0 dei danni e del tempo necessario per le riparazioni. I funzionari del parco stanno monitorando la situazione e forniranno aggiornamenti man mano che saranno disponibili ulteriori informazioni.<\/p>","protected":false},"excerpt":{"rendered":"<p>Alluvioni estreme devastano il Parco Nazionale di Yellowstone, costringendo chiusure ed evacuazioni Inondazioni senza precedenti Il Parco Nazionale di Yellowstone \u00e8 stato colpito da inondazioni senza precedenti, costringendo alla chiusura&hellip;<\/p>\n","protected":false},"author":1,"featured_media":24291,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[212],"tags":[747,283,34,1945,4682],"class_list":["post-2256","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-earth-science","tag-flooding","tag-environment","tag-climate-change","tag-natural-disasters","tag-yellowstone-national-park"],"_links":{"self":[{"href":"https:\/\/www.lifescienceart.com\/it\/wp-json\/wp\/v2\/posts\/2256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lifescienceart.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lifescienceart.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lifescienceart.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lifescienceart.com\/it\/wp-json\/wp\/v2\/comments?post=2256"}],"version-history":[{"count":2,"href":"https:\/\/www.lifescienceart.com\/it\/wp-json\/wp\/v2\/posts\/2256\/revisions"}],"predecessor-version":[{"id":24292,"href":"https:\/\/www.lifescienceart.com\/it\/wp-json\/wp\/v2\/posts\/2256\/revisions\/24292"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lifescienceart.com\/it\/wp-json\/wp\/v2\/media\/24291"}],"wp:attachment":[{"href":"https:\/\/www.lifescienceart.com\/it\/wp-json\/wp\/v2\/media?parent=2256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lifescienceart.com\/it\/wp-json\/wp\/v2\/categories?post=2256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lifescienceart.com\/it\/wp-json\/wp\/v2\/tags?post=2256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}