{"id":7190,"count":2,"description":"","link":"https:\/\/www.lifescienceart.com\/it\/tag\/experimental-archaeology\/","name":"Archeologia sperimentale","slug":"experimental-archaeology","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.lifescienceart.com\/it\/wp-json\/wp\/v2\/tags\/7190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lifescienceart.com\/it\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.lifescienceart.com\/it\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.lifescienceart.com\/it\/wp-json\/wp\/v2\/posts?tags=7190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}