{"id":3404,"count":1,"description":"","link":"https:\/\/www.lifescienceart.com\/ko\/science\/archaeological-science\/","name":"\uace0\uace0\ud559 \uacfc\ud559","slug":"archaeological-science","taxonomy":"category","parent":3,"meta":[],"_links":{"self":[{"href":"https:\/\/www.lifescienceart.com\/ko\/wp-json\/wp\/v2\/categories\/3404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lifescienceart.com\/ko\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.lifescienceart.com\/ko\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.lifescienceart.com\/ko\/wp-json\/wp\/v2\/categories\/3"}],"wp:post_type":[{"href":"https:\/\/www.lifescienceart.com\/ko\/wp-json\/wp\/v2\/posts?categories=3404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}