{"id":14203,"date":"2024-06-06T15:41:13","date_gmt":"2024-06-06T15:41:13","guid":{"rendered":"https:\/\/www.lifescienceart.com\/?p=14203"},"modified":"2024-06-06T15:41:13","modified_gmt":"2024-06-06T15:41:13","slug":"spectacular-2000-year-old-roman-dagger-unearthed","status":"publish","type":"post","link":"https:\/\/www.lifescienceart.com\/pt\/science\/archaeology\/spectacular-2000-year-old-roman-dagger-unearthed\/","title":{"rendered":"Maravilha arqueol\u00f3gica: espetacular adaga romana de 2.000 anos descoberta"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Maravilha arqueol\u00f3gica: espetacular adaga romana de 2.000 anos descoberta<\/h2>\n\n<h2 class=\"wp-block-heading\">Descoberta e restaura\u00e7\u00e3o<\/h2>\n\n<p>Em uma not\u00e1vel descoberta arqueol\u00f3gica, um estagi\u00e1rio de 19 anos chamado Nico Calman desenterrou uma espetacular adaga romana que remonta a 2.000 anos atr\u00e1s. A l\u00e2mina decorada com primor e sua bainha foram encontradas no t\u00famulo de um soldado no s\u00edtio arqueol\u00f3gico de Haltern am See, na Alemanha.<\/p>\n\n<p>Apesar de s\u00e9culos de corros\u00e3o, a arma foi meticulosamente restaurada ao longo de nove meses, revelando uma l\u00e2mina e uma bainha ricamente ornamentadas. O processo de restaura\u00e7\u00e3o envolveu jateamento de areia e esmerilhamento para devolver ao artefato seu antigo esplendor.<\/p>\n\n<h2 class=\"wp-block-heading\">Significado hist\u00f3rico<\/h2>\n\n<p>A adaga data do per\u00edodo augusto, que se estendeu de 37 a.C. a 14 d.C. Este per\u00edodo testemunhou algumas das derrotas mais humilhantes do in\u00edcio da hist\u00f3ria romana, particularmente nas m\u00e3os das tribos germ\u00e2nicas. Haltern am See, onde a adaga foi encontrada, era uma base militar nos confins do vasto imp\u00e9rio romano.<\/p>\n\n<p>A descoberta da adaga fornece informa\u00e7\u00f5es valiosas sobre o equipamento militar e os s\u00edmbolos de status dos soldados romanos durante este per\u00edodo tumultuado. A decora\u00e7\u00e3o elaborada e o fino artesanato sugerem que a adaga era um bem precioso para seu dono.<\/p>\n\n<h2 class=\"wp-block-heading\">Armamento e guerra<\/h2>\n\n<p>A pequena l\u00e2mina da adaga, medindo 13 polegadas de comprimento, provavelmente era usada como arma reserva em combate corpo a corpo. Espadas eram as armas principais dos soldados romanos, mas as adagas eram utilizadas quando as espadas eram perdidas ou danificadas.<\/p>\n\n<p>Apesar de sua apar\u00eancia delicada, a adaga era uma arma formid\u00e1vel em m\u00e3os h\u00e1beis. Sua l\u00e2mina de ferro afiada e c\u00f4nica e seu design ranhurado garantiam a m\u00e1xima efici\u00eancia de corte.<\/p>\n\n<h2 class=\"wp-block-heading\">Costumes funer\u00e1rios<\/h2>\n\n<p>A presen\u00e7a da adaga na sepultura do soldado \u00e9 incomum, uma vez que os soldados romanos normalmente n\u00e3o eram enterrados com seu equipamento militar. Isso sugere que a adaga tinha um significado especial para seu dono ou que ele foi enterrado \u00e0s pressas durante um per\u00edodo particularmente ca\u00f3tico.<\/p>\n\n<h2 class=\"wp-block-heading\">Preserva\u00e7\u00e3o e exibi\u00e7\u00e3o<\/h2>\n\n<p>O excelente estado da adaga \u00e9 uma prova da habilidade dos restauradores. O cabo e a bainha reluzentes, incrustados com prata e vidro, exibem o intrincado trabalho artesanal dos antigos artes\u00e3os romanos. A bainha forrada de madeira, adornada com esmalte vermelho, acrescenta ao apelo est\u00e9tico da adaga.<\/p>\n\n<p>A adaga restaurada ser\u00e1 exibida no Museu de Hist\u00f3ria Romana de Haltern em 2022, onde oferecer\u00e1 aos visitantes um vislumbre da vida e dos costumes dos soldados romanos durante o per\u00edodo augusto.<\/p>","protected":false},"excerpt":{"rendered":"<p>Maravilha arqueol\u00f3gica: espetacular adaga romana de 2.000 anos descoberta Descoberta e restaura\u00e7\u00e3o Em uma not\u00e1vel descoberta arqueol\u00f3gica, um estagi\u00e1rio de 19 anos chamado Nico Calman desenterrou uma espetacular adaga romana&hellip;<\/p>\n","protected":false},"author":6,"featured_media":23571,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[191],"tags":[19088,88,27,3481,89],"class_list":["post-14203","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archaeology","tag-ancient-weapons","tag-archaeology","tag-history","tag-roman-empire","tag-cultural-heritage"],"_links":{"self":[{"href":"https:\/\/www.lifescienceart.com\/pt\/wp-json\/wp\/v2\/posts\/14203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lifescienceart.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lifescienceart.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lifescienceart.com\/pt\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lifescienceart.com\/pt\/wp-json\/wp\/v2\/comments?post=14203"}],"version-history":[{"count":1,"href":"https:\/\/www.lifescienceart.com\/pt\/wp-json\/wp\/v2\/posts\/14203\/revisions"}],"predecessor-version":[{"id":14204,"href":"https:\/\/www.lifescienceart.com\/pt\/wp-json\/wp\/v2\/posts\/14203\/revisions\/14204"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lifescienceart.com\/pt\/wp-json\/wp\/v2\/media\/23571"}],"wp:attachment":[{"href":"https:\/\/www.lifescienceart.com\/pt\/wp-json\/wp\/v2\/media?parent=14203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lifescienceart.com\/pt\/wp-json\/wp\/v2\/categories?post=14203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lifescienceart.com\/pt\/wp-json\/wp\/v2\/tags?post=14203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}