{"id":6617,"date":"2021-09-16T00:19:28","date_gmt":"2021-09-16T00:19:28","guid":{"rendered":"https:\/\/www.lifescienceart.com\/pt\/?p=6617"},"modified":"2021-09-16T00:19:28","modified_gmt":"2021-09-16T00:19:28","slug":"red-flowering-currant-growing-and-care-guide","status":"publish","type":"post","link":"https:\/\/www.lifescienceart.com\/pt\/life\/nature\/red-flowering-currant-growing-and-care-guide\/","title":{"rendered":"Groselha vermelha: guia de cultivo e cuidados"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Groselha vermelha: guia de cultivo e cuidados<\/h2>\n\n<h2 class=\"wp-block-heading\">Informa\u00e7\u00f5es gerais<\/h2>\n\n<p>A groselha vermelha (Ribes sanguineum) \u00e9 um arbusto grande, perfumado e de flora\u00e7\u00e3o primaveril nativo do noroeste dos Estados Unidos. Seus vistosos cachos de flores s\u00e3o uma fonte favorita de n\u00e9ctar para beija-flores e outros polinizadores, e suas bagas comest\u00edveis, por\u00e9m sem gra\u00e7a, de cor azul-escura, fornecem alimento para a vida selvagem local no outono.<\/p>\n\n<p>Com sua forma ereta e atraente, este arbusto tolerante \u00e0 seca \u00e9 um complemento ideal para a parte traseira das bordas, como planta ornamental ou sebe informal, ou em encostas rochosas para ajudar a controlar a eros\u00e3o.<\/p>\n\n<h2 class=\"wp-block-heading\">Plantio<\/h2>\n\n<ul class=\"wp-block-list\">\n<li><strong>Escolha do local:<\/strong> As groselhas vermelhas preferem pleno sol ou meia-sombra, com mais sombra em \u00e1reas internas mais quentes e mais sol em locais costeiros. Eles requerem solo bem drenado com pH ligeiramente \u00e1cido a neutro.<\/li>\n<li><strong>Espa\u00e7amento:<\/strong> Plante os arbustos com pelo menos 6 p\u00e9s de dist\u00e2ncia para permitir fluxo de ar adequado e reduzir o risco de doen\u00e7as.<\/li>\n<li><strong>\u00c9poca:<\/strong> A melhor \u00e9poca para plantar groselhas vermelhas \u00e9 no in\u00edcio do outono ou in\u00edcio da primavera, quando o solo est\u00e1 \u00famido.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\">Cuidados<\/h2>\n\n<ul class=\"wp-block-list\">\n<li><strong>Rega:<\/strong> Regue os arbustos rec\u00e9m-plantados regularmente, especialmente durante os ver\u00f5es quentes e secos. Arbustos estabelecidos s\u00e3o tolerantes \u00e0 seca, mas apreciam regas profundas ocasionais para promover um crescimento vigoroso.<\/li>\n<li><strong>Fertiliza\u00e7\u00e3o:<\/strong> As groselhas vermelhas prosperam em solos pobres e geralmente n\u00e3o requerem fertilizantes. No entanto, adicionar um pouco de mat\u00e9ria org\u00e2nica ao solo antes do plantio pode estimular um crescimento mais vigoroso e uma flora\u00e7\u00e3o abundante.<\/li>\n<li><strong>Poda:<\/strong> A poda n\u00e3o \u00e9 essencial, mas pode ajudar a promover uma forma elegante, espessa e compacta e uma flora\u00e7\u00e3o abundante. Pode at\u00e9 um ter\u00e7o da altura do arbusto em novos brotos logo ap\u00f3s o fim da flora\u00e7\u00e3o.<\/li>\n<li><strong>Pragas e doen\u00e7as:<\/strong> As groselhas vermelhas s\u00e3o geralmente resistentes a pragas e doen\u00e7as, mas podem ser suscet\u00edveis a pulg\u00f5es e \u00e0 mosca da groselha. Monitore essas pragas e tome as medidas de controle adequadas, se necess\u00e1rio.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\">Propaga\u00e7\u00e3o<\/h2>\n\n<p>As groselhas vermelhas podem ser propagadas por estacas ou sementes:<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Estacas:<\/strong> Colete estacas de madeira macia no final da primavera ou in\u00edcio do ver\u00e3o, ou estacas de madeira dura no final do outono ou inverno. Mergulhe as estacas em um horm\u00f4nio de enraizamento e plante-as em solo bem drenado.<\/li>\n<li><strong>Sementes:<\/strong> Colete sementes de frutas maduras no final do ver\u00e3o. Armazene-as em local fresco e seco e semeie-as no outono ou estratifique-as por um a tr\u00eas meses antes de seme\u00e1-las no in\u00edcio da primavera.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\">Flora\u00e7\u00e3o<\/h2>\n\n<p>Os cachos espetaculares e extensos de flores perfumadas de flora\u00e7\u00e3o precoce s\u00e3o o motivo pelo qual muitos jardineiros cultivam o arbusto de groselha vermelha. As belezas vermelhas, rosas ou brancas cheias de n\u00e9ctar tornam essas plantas atraentes para os beija-flores e oferecem cores brilhantes no jardim no in\u00edcio da primavera.<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>\u00c9poca:<\/strong> As groselhas vermelhas geralmente florescem no in\u00edcio ou meados da primavera, por volta de abril a maio, ao mesmo tempo em que a nova folhagem come\u00e7a a surgir.<\/li>\n<li><strong>Cor e fragr\u00e2ncia:<\/strong> As flores crescem em cachos pendentes de 1 a 3 polegadas de comprimento, e cada cacho cont\u00e9m entre cinco e 30 flores individuais. Cada flor tem cinco p\u00e9talas e emite uma fragr\u00e2ncia que alguns descrevem como levemente picante.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\">Informa\u00e7\u00f5es adicionais<\/h2>\n\n<ul class=\"wp-block-list\">\n<li>A groselha vermelha n\u00e3o \u00e9 considerada invasiva nos Estados Unidos, mas \u00e9 classificada como esp\u00e9cie invasora na Nova Zel\u00e2ndia.<\/li>\n<li>As bagas de groselha vermelha s\u00e3o comest\u00edveis, mas sem gra\u00e7a. Eles podem ser usadas para fazer xaropes, geleias e conservas.<\/li>\n<li>As groselhas vermelhas podem atingir at\u00e9 10 p\u00e9s ou mais de altura quando as condi\u00e7\u00f5es s\u00e3o adequadas. Muitas variedades t\u00eam h\u00e1bitos mais compactos, geralmente atingindo apenas 6 a 8 p\u00e9s quando totalmente estabelecidas.<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Groselha vermelha: guia de cultivo e cuidados Informa\u00e7\u00f5es gerais A groselha vermelha (Ribes sanguineum) \u00e9 um arbusto grande, perfumado e de flora\u00e7\u00e3o primaveril nativo do noroeste dos Estados Unidos. Seus&hellip;<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3115],"tags":[11055,2639,8848,8819,1141],"class_list":["post-6617","post","type-post","status-publish","format-standard","hentry","category-nature","tag-red-flowering-currant","tag-wildlife-habitat","tag-gardening","tag-landscaping","tag-pollinators"],"_links":{"self":[{"href":"https:\/\/www.lifescienceart.com\/pt\/wp-json\/wp\/v2\/posts\/6617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lifescienceart.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lifescienceart.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lifescienceart.com\/pt\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lifescienceart.com\/pt\/wp-json\/wp\/v2\/comments?post=6617"}],"version-history":[{"count":1,"href":"https:\/\/www.lifescienceart.com\/pt\/wp-json\/wp\/v2\/posts\/6617\/revisions"}],"predecessor-version":[{"id":6618,"href":"https:\/\/www.lifescienceart.com\/pt\/wp-json\/wp\/v2\/posts\/6617\/revisions\/6618"}],"wp:attachment":[{"href":"https:\/\/www.lifescienceart.com\/pt\/wp-json\/wp\/v2\/media?parent=6617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lifescienceart.com\/pt\/wp-json\/wp\/v2\/categories?post=6617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lifescienceart.com\/pt\/wp-json\/wp\/v2\/tags?post=6617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}